{"id":1214,"date":"2024-11-07T13:45:41","date_gmt":"2024-11-07T12:45:41","guid":{"rendered":"https:\/\/www.costruzionidegiuli.it\/?page_id=1214"},"modified":"2024-11-09T11:40:29","modified_gmt":"2024-11-09T10:40:29","slug":"bifamiliare-rosolina","status":"publish","type":"page","link":"https:\/\/www.costruzionidegiuli.it\/index.php\/bifamiliare-rosolina\/","title":{"rendered":"Bifamiliare &#8211; Rosolina"},"content":{"rendered":"\n<div class=\"wp-block-citadela-blocks-spacer citadela-block-spacer\"><div class=\"inner-holder\" style=\"padding-top:50px\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-citadela-blocks-custom-container citadela-block-custom-container size-wide bg-type-none inside-space-none\"><div class=\"inner-holder\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1-1024x707.png\" alt=\"\" class=\"wp-image-1272 size-full\" srcset=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1-1024x707.png 1024w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1-300x207.png 300w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1-768x530.png 768w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.A-1.png 1042w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5bbd94b6939f7cdf707e9ae2d3c2d1ee\" style=\"font-size:20px\"><strong>Bifamiliare &#8211; Vendita &#8211; Rosolina,  via Marinai d&#8217;Italia<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-59fa726cac5fddb5d9ffb2b4ab4ece5f\" style=\"font-size:18px\">Fabbricato residenziale bifamiliare in fase di realizzazione in classe energetica A. Unit\u00e0 residenziale al piano terra e primo, accesso indipendente ed area esclusiva, composta al piano terra da ingresso, soggiorno, cucina abitabile, corridoio, bagno e garage comunicante, mentre al piano primo da corridoio, tre letto, bagno ed un terrazzo. Finiture personalizzabili e possibili modifiche in corso di costruzione. Agevolazioni fiscali del costo di costruzione del garage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"40\" src=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-2.png\" alt=\"\" class=\"wp-image-1217\" srcset=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-2.png 480w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-2-300x25.png 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-citadela-blocks-spacer citadela-block-spacer\"><div class=\"inner-holder\" style=\"padding-top:40px\"><\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-citadela-blocks-spacer citadela-block-spacer\"><div class=\"inner-holder\" style=\"padding-top:40px\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-citadela-blocks-custom-container citadela-block-custom-container size-wide bg-type-none inside-space-none\"><div class=\"inner-holder\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:25% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1-1024x707.png\" alt=\"\" class=\"wp-image-1273 size-full\" srcset=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1-1024x707.png 1024w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1-300x207.png 300w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1-768x530.png 768w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/Rosolina-Bif.B-1.png 1039w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5bbd94b6939f7cdf707e9ae2d3c2d1ee\" style=\"font-size:20px\"><strong>Bifamiliare &#8211; Vendita &#8211; Rosolina,  via Marinai d&#8217;Italia<\/strong><\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-59fa726cac5fddb5d9ffb2b4ab4ece5f\" style=\"font-size:18px\">Fabbricato residenziale bifamiliare in fase di realizzazione in classe energetica A. Unit\u00e0 residenziale al piano terra e primo, accesso indipendente ed area esclusiva, composta al piano terra da ingresso, soggiorno, cucina abitabile, corridoio, bagno e garage comunicante, mentre al piano primo da corridoio, tre letto, bagno ed un terrazzo. Finiture personalizzabili e possibili modifiche in corso di costruzione. Agevolazioni fiscali del costo di costruzione del garage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"40\" src=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-8.png\" alt=\"\" class=\"wp-image-1220\" srcset=\"https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-8.png 480w, https:\/\/www.costruzionidegiuli.it\/wp-content\/uploads\/2024\/11\/5_2_160_24-8-300x25.png 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-citadela-blocks-spacer citadela-block-spacer\"><div class=\"inner-holder\" style=\"padding-top:40px\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_themeisle_gutenberg_block_has_review":false,"_citadela_hide_page_title":"1","_citadela_remove_header_space":"1","_citadela_custom_class":"","_citadela_half_map_provider":"","_citadela_half_map_theme":"","_citadela_half_map_themeOSM":"","_citadela_half_map_customTheme":"","_citadela_half_map_dataType":"","_citadela_half_map_dynamicTrack":false,"_citadela_half_map_trackColor":"","_citadela_half_map_trackEndpointsColor":"","_citadela_half_map_filterCategory":"","_citadela_half_map_filterLocation":"","_citadela_half_map_filterFeatured":false,"_citadela_half_map_noDataBehavior":"empty-map","_citadela_half_map_noDataText":"","_citadela_half_map_clusterGridSize":80,"_citadela_header":false,"_citadela_header_over_content":false,"_citadela_header_text_color":"","_citadela_header_logo":[],"_citadela_header_bg_image":[],"_citadela_header_bg_position":{"x":0.5,"y":0.5},"_citadela_header_bg_size":"cover","_citadela_header_bg_repeat":"no-repeat","_citadela_header_bg_fixed":false,"_citadela_header_bg_color":"","_citadela_header_bg_image_overlay":"","_citadela_header_transparent_bg":false,"_citadela_content_width":"","_citadela_half_layout_position":"","footnotes":""},"class_list":["post-1214","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/pages\/1214"}],"collection":[{"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/comments?post=1214"}],"version-history":[{"count":5,"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/pages\/1214\/revisions"}],"predecessor-version":[{"id":1274,"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/pages\/1214\/revisions\/1274"}],"wp:attachment":[{"href":"https:\/\/www.costruzionidegiuli.it\/index.php\/wp-json\/wp\/v2\/media?parent=1214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}